{"id":272,"date":"2010-05-02T19:25:03","date_gmt":"2010-05-02T19:25:03","guid":{"rendered":"https:\/\/www.visiterarles.com\/?p=272"},"modified":"2010-06-20T15:01:26","modified_gmt":"2010-06-20T15:01:26","slug":"fete-des-vignerons-des-baux-a-saint-remy-de-provence","status":"publish","type":"post","link":"https:\/\/www.visiterarles.com\/en\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/","title":{"rendered":"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin"},"content":{"rendered":"<p><a href=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480.jpg\"><img decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-366\" title=\"vignerons 2 [640x480]\" src=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-150x150.jpg 150w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-300x300.jpg 300w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-30x30.jpg 30w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-84x84.jpg 84w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480-185x185.jpg 185w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x480.jpg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>Les vignerons des Baux\u00a0s&rsquo;associent \u00e0 Taco and Co pour vous inviter Samedi\u00a026 juin\u00a0\u00e0 la f\u00eate des vignerons des Baux \u00e0 Saint Remy de Provence .<\/p>\n<figure id=\"attachment_279\" aria-describedby=\"caption-attachment-279\" style=\"width: 225px\" class=\"wp-caption aligncenter\"><a title=\"f\u00eate des vignerons Baux de provence\" href=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/P4300001-640x4801.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-279\" title=\"f\u00eate des vignerons Baux de  provence\" src=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/P4300001-640x4801-225x300.jpg\" alt=\"f\u00eate des vignerons Baux de provence\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/P4300001-640x4801-225x300.jpg 225w, https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/P4300001-640x4801.jpg 480w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-279\" class=\"wp-caption-text\">f\u00eate des vignerons Baux de provence<\/figcaption><\/figure>\n<p>Les vignerons vous attendent de 10h00 \u00e0 18h00, place Laugier pour vous faire d\u00e9guster leurs vins.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les vignerons des Baux\u00a0s&rsquo;associent \u00e0 Taco and Co pour vous inviter Samedi\u00a026 juin\u00a0\u00e0 la f\u00eate des vignerons des Baux \u00e0 Saint Remy de Provence . Les vignerons vous attendent de 10h00 \u00e0 18h00, place Laugier pour vous faire d\u00e9guster leurs vins.<\/p>","protected":false},"author":2,"featured_media":367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin - Visiter Arles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visiterarles.com\/en\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"damien\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\"},\"author\":{\"name\":\"damien\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/0ef93571b2fe272c676137a002139d56\"},\"headline\":\"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin\",\"datePublished\":\"2010-05-02T19:25:03+00:00\",\"dateModified\":\"2010-06-20T15:01:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\"},\"wordCount\":68,\"publisher\":{\"@id\":\"https:\/\/www.visiterarles.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg\",\"articleSection\":[\"accueil\",\"Actualit\u00e9s\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\",\"url\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\",\"name\":\"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin - Visiter Arles\",\"isPartOf\":{\"@id\":\"https:\/\/www.visiterarles.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg\",\"datePublished\":\"2010-05-02T19:25:03+00:00\",\"dateModified\":\"2010-06-20T15:01:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage\",\"url\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg\",\"contentUrl\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg\",\"width\":\"480\",\"height\":\"480\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.visiterarles.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#website\",\"url\":\"https:\/\/www.visiterarles.com\/en\/\",\"name\":\"Visiter Arles\",\"description\":\"Tourisme en Provence \u00e0 Arles\",\"publisher\":{\"@id\":\"https:\/\/www.visiterarles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.visiterarles.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#organization\",\"name\":\"Visiter Arles\",\"url\":\"https:\/\/www.visiterarles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2017\/10\/taco-and-co-1-1.jpg\",\"contentUrl\":\"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2017\/10\/taco-and-co-1-1.jpg\",\"width\":124,\"height\":73,\"caption\":\"Visiter Arles\"},\"image\":{\"@id\":\"https:\/\/www.visiterarles.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/0ef93571b2fe272c676137a002139d56\",\"name\":\"damien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7a0d4f0af72a2d627adac81a8c10a5b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7a0d4f0af72a2d627adac81a8c10a5b6?s=96&d=mm&r=g\",\"caption\":\"damien\"},\"url\":\"https:\/\/www.visiterarles.com\/en\/blog\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin - Visiter Arles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visiterarles.com\/en\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/","twitter_misc":{"Written by":"damien"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#article","isPartOf":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/"},"author":{"name":"damien","@id":"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/0ef93571b2fe272c676137a002139d56"},"headline":"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin","datePublished":"2010-05-02T19:25:03+00:00","dateModified":"2010-06-20T15:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/"},"wordCount":68,"publisher":{"@id":"https:\/\/www.visiterarles.com\/en\/#organization"},"image":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg","articleSection":["accueil","Actualit\u00e9s"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/","url":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/","name":"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin - Visiter Arles","isPartOf":{"@id":"https:\/\/www.visiterarles.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage"},"image":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg","datePublished":"2010-05-02T19:25:03+00:00","dateModified":"2010-06-20T15:01:26+00:00","breadcrumb":{"@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#primaryimage","url":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg","contentUrl":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2010\/05\/vignerons-2-640x4801.jpg","width":"480","height":"480"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visiterarles.com\/blog\/2010\/05\/02\/fete-des-vignerons-des-baux-a-saint-remy-de-provence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visiterarles.com\/"},{"@type":"ListItem","position":2,"name":"F\u00eate des vignerons des Baux \u00e0 Saint-Remy de provence le samedi 26 juin"}]},{"@type":"WebSite","@id":"https:\/\/www.visiterarles.com\/en\/#website","url":"https:\/\/www.visiterarles.com\/en\/","name":"Visiter Arles","description":"Tourisme en Provence \u00e0 Arles","publisher":{"@id":"https:\/\/www.visiterarles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visiterarles.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.visiterarles.com\/en\/#organization","name":"Visiter Arles","url":"https:\/\/www.visiterarles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.visiterarles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2017\/10\/taco-and-co-1-1.jpg","contentUrl":"https:\/\/www.visiterarles.com\/wp-content\/uploads\/2017\/10\/taco-and-co-1-1.jpg","width":124,"height":73,"caption":"Visiter Arles"},"image":{"@id":"https:\/\/www.visiterarles.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/0ef93571b2fe272c676137a002139d56","name":"damien","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.visiterarles.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7a0d4f0af72a2d627adac81a8c10a5b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a0d4f0af72a2d627adac81a8c10a5b6?s=96&d=mm&r=g","caption":"damien"},"url":"https:\/\/www.visiterarles.com\/en\/blog\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/posts\/272"}],"collection":[{"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":0,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/media\/367"}],"wp:attachment":[{"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visiterarles.com\/en\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}